{"id":10265,"date":"2023-07-09T10:42:14","date_gmt":"2023-07-09T10:42:14","guid":{"rendered":"https:\/\/devsedu.softatomic.com\/?page_id=10265"},"modified":"2026-06-11T22:39:22","modified_gmt":"2026-06-11T20:39:22","slug":"sobre-mim","status":"publish","type":"page","link":"https:\/\/julikrolop.com\/pt\/ueber-mich\/","title":{"rendered":"Sobre"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"10265\" class=\"elementor elementor-10265\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-20c021d elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"20c021d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd46579\" data-id=\"dd46579\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-81695c6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"81695c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-628cbe7\" data-id=\"628cbe7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ddcf37 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ddcf37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9f4867\" data-id=\"f9f4867\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b952ac1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b952ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>SOBRE JULY KROLOP<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-974099b edublink-br-tl-none elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"974099b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sou instrutor(a) de <span class=\"edublink-color-secondary\">Democracia, diversidade e participa\u00e7\u00e3o juvenil<\/span> <br>\ne apoiar organiza\u00e7\u00f5es para que vivam verdadeiramente esses valores.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612f22f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"612f22f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hero__tag\" role=\"listitem\"><i class=\"fas fa-users\" aria-hidden=\"true\"><\/i>\u00a0\u00a0Treinamento em Diversidade<br \/><i class=\"fas fa-landmark\" aria-hidden=\"true\"><\/i>\u00a0\u00a0Educa\u00e7\u00e3o para a democracia<br \/><\/span><span class=\"hero__tag\" role=\"listitem\"><i class=\"fas fa-bullhorn\" aria-hidden=\"true\"><\/i>\u00a0 Participa\u00e7\u00e3o dos jovens<br \/><\/span><span class=\"hero__tag\" role=\"listitem\"><i class=\"fas fa-university\" aria-hidden=\"true\"><\/i>\u00a0\u00a0Educa\u00e7\u00e3o pol\u00edtica<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e71d7d3 elementor-invisible elementor-widget elementor-widget-edublink-button\" data-id=\"e71d7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-default edublink-button-size-custom edublink-button-icon-position-after default-style\" href=\"mailto:anfragen@julikrolop.com?subject=Anfrage%20Workshop%20oder%20Beratung\">Fale comigo<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-312e320\" data-id=\"312e320\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b11d00a elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"b11d00a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-1.5\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/7Ativo-7.png\" alt=\"7Ativo 7\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a3bd2f elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"0a3bd2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"1.5\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/7Ativo-6.png\" alt=\"7Ativo 6\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae7ed75 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-html\" data-id=\"ae7ed75\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"edublink-hm-instructor-info edublink-bg-white edublink-color-heading edublink-radius\">\n    <div class=\"instructor-wrapper\">\n        <h5 class=\"title edublink-color-heading\">Coopera\u00e7\u00e3o<\/h5>\n        <div class=\"instructor-media\">\n            <div class=\"content\">\n                <span class=\"edublink-color-secondary edublink-p-bold\">\n                    ONGs \u2022 Universidades \u2022 Institui\u00e7\u00f5es p\u00fablicas<br>\n                <\/span>\n                Workshops e projetos por toda a Alemanha\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b069aa elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1b069aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-left&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1514\" height=\"2268\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832.jpg\" class=\"attachment-full size-full wp-image-23700\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832.jpg 1514w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-200x300.jpg 200w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-684x1024.jpg 684w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-768x1150.jpg 768w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-1025x1536.jpg 1025w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-1367x2048.jpg 1367w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/IMG_2832-8x12.jpg 8w\" sizes=\"(max-width: 1514px) 100vw, 1514px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbd0ab elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"8bbd0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/7Ativo-6.png\" alt=\"7Ativo 6\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f258fc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f258fc0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4dfd9f\" data-id=\"d4dfd9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-38201ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38201ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-39e3f1b\" data-id=\"39e3f1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b4e09 elementor-widget__width-auto elementor-widget elementor-widget-edublink-icon-box\" data-id=\"49b4e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position- edublink-svg-path-animation\" data-vivus=\"{&quot;enable&quot;:&quot;enable&quot;,&quot;type&quot;:&quot;delayed&quot;,&quot;duration&quot;:&quot;150&quot;,&quot;play_on_hover&quot;:&quot;enable&quot;,&quot;hover_left&quot;:&quot;disable&quot;}\"><div class=\"edublink-svg-icon edublink-icon-box-icon edublink-icon-box-enable\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" viewbox=\"0 0 48 40\" fill=\"none\"><path d=\"M29.1048 32.5521H2.67293C1.72721 32.5521 0.964844 31.7998 0.964844 30.8664V2.63786C0.964844 1.70453 1.72721 0.952148 2.67293 0.952148H45.3267C46.2724 0.952148 47.0348 1.70453 47.0348 2.63786V30.8664C47.0348 31.7998 46.2724 32.5521 45.3267 32.5521H41.8044\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M8.31836 9.33301H40.6658\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M8.31836 16.752H22.369\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M35.4355 28.2858C39.001 28.2858 41.8914 25.4332 41.8914 21.9144C41.8914 18.3956 39.001 15.543 35.4355 15.543C31.8699 15.543 28.9795 18.3956 28.9795 21.9144C28.9795 25.4332 31.8699 28.2858 35.4355 28.2858Z\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M30.5523 26.0762L28.0626 38.6286C28.0047 38.9238 28.3231 39.1428 28.5837 39L34.5668 35.619C35.0975 35.3143 35.7538 35.3143 36.2942 35.619L42.2773 39C42.5378 39.1524 42.8563 38.9238 42.7984 38.6286L40.3086 26.0762\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><\/svg><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">15+ <br> Anos de experi\u00eancia<\/h5><div class=\"edublink-icon-box-details\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6c01134\" data-id=\"6c01134\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1491646 elementor-widget__width-auto elementor-widget elementor-widget-edublink-icon-box\" data-id=\"1491646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position- edublink-svg-path-animation\" data-vivus=\"{&quot;enable&quot;:&quot;enable&quot;,&quot;type&quot;:&quot;delayed&quot;,&quot;duration&quot;:&quot;150&quot;,&quot;play_on_hover&quot;:&quot;enable&quot;,&quot;hover_left&quot;:&quot;disable&quot;}\"><div class=\"edublink-svg-icon edublink-icon-box-icon edublink-icon-box-enable\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"38\" height=\"36\" viewbox=\"0 0 44 40\" fill=\"none\"><path d=\"M41.37 34.7695C41.27 36.5695 39.78 37.9995 37.95 37.9995H5.42C3.6 37.9995 2.1 36.5695 2 34.7695H41.37ZM41.57 32.7695H1.81C0.81 32.7695 0 33.5795 0 34.5795C0 37.5695 2.43 39.9995 5.42 39.9995H37.95C40.94 39.9995 43.37 37.5695 43.37 34.5795C43.38 33.5795 42.57 32.7695 41.57 32.7695Z\" fill=\"#ffffff\"><\/path><path d=\"M38.3501 15.5801V33.6801H4.12012V9.27012C4.12012 8.77012 4.52012 8.37012 5.02012 8.37012H28.0001\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M41.3801 2V14.27H31.9901C31.3001 14.27 30.6301 14.52 30.1101 14.96L29.1101 15.64V2H41.3801ZM41.5701 0H28.9201C27.9201 0 27.1101 0.81 27.1101 1.81V17.89C27.1101 18.39 27.5201 18.72 27.9401 18.72C28.1401 18.72 28.3501 18.64 28.5201 18.48L31.3501 16.54C31.5201 16.37 31.7501 16.27 31.9901 16.27H41.5701C42.5701 16.27 43.3801 15.46 43.3801 14.46V1.81C43.3801 0.81 42.5701 0 41.5701 0Z\" fill=\"#ffffff\"><\/path><path d=\"M32.0801 6.12988H38.4101\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M33.8899 10.1396H36.5899\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M10.9399 33.6701V26.7001C10.9399 24.5601 12.9599 22.8301 15.4599 22.8301C17.9599 22.8301 19.9799 24.5601 19.9799 26.7001V33.6701\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M15.46 22.8302C16.9567 22.8302 18.17 21.6168 18.17 20.1202C18.17 18.6235 16.9567 17.4102 15.46 17.4102C13.9633 17.4102 12.75 18.6235 12.75 20.1202C12.75 21.6168 13.9633 22.8302 15.46 22.8302Z\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><\/svg><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Workshops e <br> Treinamento<\/h5><div class=\"edublink-icon-box-details\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-20d01d3\" data-id=\"20d01d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9975995 elementor-widget__width-auto elementor-widget elementor-widget-edublink-icon-box\" data-id=\"9975995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position- edublink-svg-path-animation\" data-vivus=\"{&quot;enable&quot;:&quot;enable&quot;,&quot;type&quot;:&quot;delayed&quot;,&quot;duration&quot;:&quot;150&quot;,&quot;play_on_hover&quot;:&quot;enable&quot;,&quot;hover_left&quot;:&quot;disable&quot;}\"><div class=\"edublink-svg-icon edublink-icon-box-icon edublink-icon-box-enable\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" viewbox=\"0 0 48 40\" fill=\"none\"><path d=\"M29.1048 32.5521H2.67293C1.72721 32.5521 0.964844 31.7998 0.964844 30.8664V2.63786C0.964844 1.70453 1.72721 0.952148 2.67293 0.952148H45.3267C46.2724 0.952148 47.0348 1.70453 47.0348 2.63786V30.8664C47.0348 31.7998 46.2724 32.5521 45.3267 32.5521H41.8044\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M8.31836 9.33301H40.6658\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M8.31836 16.752H22.369\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M35.4355 28.2858C39.001 28.2858 41.8914 25.4332 41.8914 21.9144C41.8914 18.3956 39.001 15.543 35.4355 15.543C31.8699 15.543 28.9795 18.3956 28.9795 21.9144C28.9795 25.4332 31.8699 28.2858 35.4355 28.2858Z\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M30.5523 26.0762L28.0626 38.6286C28.0047 38.9238 28.3231 39.1428 28.5837 39L34.5668 35.619C35.0975 35.3143 35.7538 35.3143 36.2942 35.619L42.2773 39C42.5378 39.1524 42.8563 38.9238 42.7984 38.6286L40.3086 26.0762\" fill=\"none\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><\/svg><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Alemanha <br> &amp; Brasil<\/h5><div class=\"edublink-icon-box-details\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-633d57d\" data-id=\"633d57d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c111b2 elementor-widget__width-auto elementor-widget elementor-widget-edublink-icon-box\" data-id=\"3c111b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position- edublink-svg-path-animation\" data-vivus=\"{&quot;enable&quot;:&quot;enable&quot;,&quot;type&quot;:&quot;delayed&quot;,&quot;duration&quot;:&quot;150&quot;,&quot;play_on_hover&quot;:&quot;enable&quot;,&quot;hover_left&quot;:&quot;disable&quot;}\"><div class=\"edublink-svg-icon edublink-icon-box-icon edublink-icon-box-enable\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"38\" height=\"40\" viewbox=\"0 0 45 40\" fill=\"none\"><path d=\"M22.5004 20.4568C26.6355 20.4568 29.9876 17.1309 29.9876 13.0282C29.9876 8.92549 26.6355 5.59961 22.5004 5.59961C18.3653 5.59961 15.0132 8.92549 15.0132 13.0282C15.0132 17.1309 18.3653 20.4568 22.5004 20.4568Z\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M32.7999 39.0468H12.2005C11.6821 39.0468 11.2598 38.6277 11.2598 38.1134V31.6182C11.2598 25.4563 16.2896 20.4658 22.5002 20.4658C28.7107 20.4658 33.7406 25.4563 33.7406 31.6182V38.123C33.7406 38.6277 33.3182 39.0468 32.7999 39.0468Z\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M25.6772 6.06643C26.6563 3.09501 29.4784 0.952148 32.7997 0.952148C36.9368 0.952148 40.2869 4.27596 40.2869 8.38072C40.2869 12.4855 36.9368 15.8093 32.7997 15.8093C31.6862 15.8093 30.6303 15.5712 29.68 15.1331\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M29.1714 16.4088C30.3137 16.0279 31.5327 15.8184 32.7998 15.8184C39.0103 15.8184 44.0402 20.8088 44.0402 26.9707V33.4755C44.0402 33.9898 43.6178 34.4088 43.0995 34.4088H33.9133\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M19.3229 6.06643C18.3342 3.09501 15.5217 0.952148 12.2004 0.952148C8.06325 0.952148 4.70361 4.27596 4.70361 8.38072C4.70361 12.4855 8.05366 15.8093 12.1908 15.8093C13.3043 15.8093 14.3602 15.5712 15.3105 15.1331\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><path d=\"M15.8288 16.4088C14.6865 16.0279 13.4674 15.8184 12.2004 15.8184C5.98982 15.8184 0.959961 20.8088 0.959961 26.9707V33.4755C0.959961 33.9898 1.38232 34.4088 1.90066 34.4088H11.0869\" stroke=\"#ffffff\" stroke-width=\"2\" stroke-miterlimit=\"10\"><\/path><\/svg><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Universidades, <br> ONGs e munic\u00edpios<\/h5><div class=\"edublink-icon-box-details\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-86fc28e e-flex e-con-boxed e-con e-parent\" data-id=\"86fc28e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-372ad77 e-con-full e-flex e-con e-child\" data-id=\"372ad77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e18e68e edublink-br-tp-none elementor-widget elementor-widget-edublink-heading\" data-id=\"e18e68e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Minha convic\u00e7\u00e3o<\/span><h3 class=\"heading\">Por que eu? <br>\n<mark>Eu fa\u00e7o este trabalho<\/mark><\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p data-start=\"1394\" data-end=\"1592\">Para mim, a democracia n\u00e3o come\u00e7a nas institui\u00e7\u00f5es pol\u00edticas. Ela come\u00e7a onde as pessoas conversam, se escutam, enfrentam conflitos e tomam decis\u00f5es juntas.<\/p><p data-start=\"1594\" data-end=\"1796\">Meu trabalho nasce da convic\u00e7\u00e3o de que a participa\u00e7\u00e3o deve ser aprendida, vivenciada e praticada, especialmente onde diferentes perspectivas, experi\u00eancias e din\u00e2micas de poder se chocam.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ec5364a e-con-full e-flex e-con e-child\" data-id=\"ec5364a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf8536 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-html\" data-id=\"3bf8536\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"edublink-hm-instructor-info edublink-bg-white edublink-color-heading edublink-radius\">\n    <div class=\"instructor-wrapper\">\n        <h5 class=\"title edublink-color-heading\">Pensamento de julho<\/h5>\n\n        <div class=\"instructor-media\">\n            <div class=\"content\" style=\"position: relative; padding-left: 18px; border-left: 4px solid #ff6b3d;\">\n                <span style=\"font-size: 34px; line-height: 1; color: #8b2bbf; font-weight: 700; display: block; margin-bottom: 4px;\">\n                    \u201c\n                <\/span>\n\n                <span class=\"edublink-color-secondary edublink-p-bold\" style=\"font-size: 20px; line-height: 1.35; display: block; margin-bottom: 10px;\">\n                    A democracia n\u00e3o \u00e9 um estado que se conquista.\n                <\/span>\n\n                <span style=\"font-size: 15px; line-height: 1.7; display: block;\">\n                    \u00c9 uma pr\u00e1tica di\u00e1ria em conversas, decis\u00f5es e na forma como interagimos uns com os outros.\n                <\/span>\n\n                <span style=\"font-size: 13px; line-height: 1.5; display: block; margin-top: 16px; color: #8b2bbf; font-weight: 700; letter-spacing: 0.3px;\">\n                    JULHO KROLOP\n                <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d1dc829 e-flex e-con-boxed e-con e-parent\" data-id=\"d1dc829\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0da1369 e-con-full e-flex e-con e-child\" data-id=\"0da1369\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2829d15 edublink-br-tp-none elementor-widget elementor-widget-edublink-heading\" data-id=\"2829d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Minha experi\u00eancia<\/span><h3 class=\"heading\">Mais de 15 anos em <br>\n<mark>Educa\u00e7\u00e3o e Participa\u00e7\u00e3o<\/mark><\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p data-start=\"1394\" data-end=\"1592\">Combino educa\u00e7\u00e3o pol\u00edtica, treinamento em diversidade, alfabetiza\u00e7\u00e3o midi\u00e1tica e participa\u00e7\u00e3o juvenil em uma pr\u00e1tica que realmente alcan\u00e7a as pessoas.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2aba67 elementor-widget elementor-widget-eael-content-timeline\" data-id=\"d2aba67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-content-timeline.default\">\n\t\t\t\t\t\t\t<div id=\"eael-content-timeline-d2aba67\" class=\"content-timeline-layout-right date-position-inside horizontal-timeline-wrapper\" data-slide_to_scroll=\"{&quot;desktop&quot;:1,&quot;mobile&quot;:1,&quot;tablet&quot;:1}\">\n\t\t\t<div class=\"eael-content-timeline-container\">\n\t\t\t\t<div class=\"eael-content-timeline-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture\"><i class=\"far fa-circle\"><\/i><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Atual<\/span><h2 class=\"eael-timeline-title\">Respons\u00e1vel pela \u00e1rea da Educa\u00e7\u00e3o \u2013 Conselho da Juventude da Baviera (BJR)<\/h2><div class=\"eael-timeline-excerpt\"><p>Apoio aos processos de participa\u00e7\u00e3o, formatos educativos e estrat\u00e9gias para a participa\u00e7\u00e3o de crian\u00e7as e jovens na Baviera.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture\"><i class=\"far fa-circle\"><\/i><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Atual<\/span><h2 class=\"eael-timeline-title\">Docente \u2013 Universidade de Ci\u00eancias Aplicadas de Munique<\/h2><div class=\"eael-timeline-excerpt\"><p>Contribuir com minha experi\u00eancia pr\u00e1tica para a educa\u00e7\u00e3o acad\u00eamica sobre democracia, participa\u00e7\u00e3o e diversidade social.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture\"><i class=\"far fa-circle\"><\/i><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Desde 2017<\/span><h2 class=\"eael-timeline-title\">Formador freelancer \u2013 <br> Instituto JFF de Educa\u00e7\u00e3o para a M\u00eddia<\/h2><div class=\"eael-timeline-excerpt\"><p>Desenvolvimento de m\u00e9todos inovadores para promover a democracia e a diversidade no projeto &quot;Escola Democr\u00e1tica&quot; e em outros formatos de educa\u00e7\u00e3o pol\u00edtica na m\u00eddia.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture\"><i class=\"far fa-circle\"><\/i><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">10 anos<\/span><h2 class=\"eael-timeline-title\">Trabalho em centros para jovens<\/h2><div class=\"eael-timeline-excerpt\"><p>Trabalhar diretamente com jovens \u2013 criando espa\u00e7os onde eles possam expressar suas opini\u00f5es e participar ativamente.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f058d49 e-con-full e-flex e-con e-child\" data-id=\"f058d49\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd9a24 edublink-br-tp-none elementor-widget elementor-widget-edublink-heading\" data-id=\"3dd9a24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Institui\u00e7\u00f5es<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f55ed elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"57f55ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-left\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"fas fa-child\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Conselho da Juventude da Baviera (BJR)<\/h5><div class=\"edublink-icon-box-details\"><p>Respons\u00e1vel pela \u00e1rea da Educa\u00e7\u00e3o \u2013 Participa\u00e7\u00e3o de Crian\u00e7as e Jovens<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc68539 elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"fc68539\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"ri ri-bank-line\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\"> Universidade de Ci\u00eancias Aplicadas de Munique (HM)<\/h5><div class=\"edublink-icon-box-details\"><p>Docente \u2013 Democracia e Sociedade<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1c5897 elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"a1c5897\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"fas fa-photo-video\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">JFF \u2013 Instituto de Educa\u00e7\u00e3o para os Media<\/h5><div class=\"edublink-icon-box-details\"><p>Formador freelancer \u2013 Educa\u00e7\u00e3o em comunica\u00e7\u00e3o pol\u00edtica<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c936f elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"a6c936f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"fas fa-building\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\"> KJR DACHAU - Projeto \u201eEscola Democr\u00e1tica\"<\/h5><div class=\"edublink-icon-box-details\"><p>Desenvolvimento e teste de m\u00e9todos<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8741e02 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8741e02\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-10d7618 edublink-brand-opacity\" data-id=\"10d7618\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4284f4 elementor-widget elementor-widget-image\" data-id=\"e4284f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"432\" height=\"117\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/HM.png\" class=\"attachment-full size-full wp-image-22788\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/HM.png 432w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/HM-300x81.png 300w\" sizes=\"(max-width: 432px) 100vw, 432px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-15ffd77 edublink-brand-opacity\" data-id=\"15ffd77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72b5087 elementor-widget elementor-widget-image\" data-id=\"72b5087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"133\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/BJR-logo.png\" class=\"attachment-full size-full wp-image-22789\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/BJR-logo.png 500w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/BJR-logo-300x80.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-640601e edublink-brand-opacity\" data-id=\"640601e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a46bb59 elementor-widget elementor-widget-image\" data-id=\"a46bb59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"107\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/JFF-logo.png\" class=\"attachment-full size-full wp-image-22790\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/JFF-logo.png 471w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/JFF-logo-300x68.png 300w\" sizes=\"(max-width: 471px) 100vw, 471px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-96de81e edublink-brand-opacity\" data-id=\"96de81e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6eed9bd elementor-widget elementor-widget-image\" data-id=\"6eed9bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"150\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/kjr-dachau-logo.jpg\" class=\"attachment-full size-full wp-image-22791\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7480f73 edublink-brand-opacity\" data-id=\"7480f73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e126db9 elementor-widget elementor-widget-image\" data-id=\"e126db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1199\" height=\"570\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie.jpg\" class=\"attachment-full size-full wp-image-22792\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie.jpg 1199w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie-300x143.jpg 300w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie-1024x487.jpg 1024w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie-768x365.jpg 768w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Logo-Akademie-600x285.jpg 600w\" sizes=\"(max-width: 1199px) 100vw, 1199px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3c909f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c909f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b3b3431\" data-id=\"b3b3431\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dbd97a edublink-br-tp-none elementor-widget elementor-widget-edublink-heading\" data-id=\"7dbd97a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Minha hist\u00f3ria<\/span><h3 class=\"heading\">Do Brasil<br>\n<mark>para a Alemanha<\/mark><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-917a384 e-flex e-con-boxed e-con e-parent\" data-id=\"917a384\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-f3d5387-f084647\" data-interaction-id=\"f3d5387\" data-e-type=\"widget\" data-id=\"f3d5387\" id=\"23118\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-1.png\" width=\"512\" height=\"512\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-1.png 512w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-1-300x300.png 300w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-1-150x150.png 150w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-1-100x100.png 100w\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-1b5b613-acd8bc4\" data-interaction-id=\"1b5b613\" data-e-type=\"widget\" data-id=\"1b5b613\" id=\"23120\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/right-arrow.png\" width=\"512\" height=\"512\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/right-arrow.png 512w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/right-arrow-300x300.png 300w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/right-arrow-150x150.png 150w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/right-arrow-100x100.png 100w\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"e-image-base e-809ebfb-de8f641\" data-interaction-id=\"809ebfb\" data-e-type=\"widget\" data-id=\"809ebfb\" id=\"23119\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-2.png\" width=\"512\" height=\"512\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-2.png 512w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-2-300x300.png 300w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-2-150x150.png 150w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/square-2-100x100.png 100w\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8fd2d5 edublink-br-tp-none elementor-widget elementor-widget-edublink-heading\" data-id=\"e8fd2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><div class=\"sub-heading\"><p class=\"lead lead--light\">Minha jornada come\u00e7ou no Brasil e me levou \u00e0 Alemanha h\u00e1 mais de duas d\u00e9cadas.<\/p><p>Essa experi\u00eancia biogr\u00e1fica molda minha vis\u00e3o de sociedade, pertencimento, participa\u00e7\u00e3o e diversidade. Ela conecta meu trabalho profissional com uma perspectiva pessoal sobre as seguintes quest\u00f5es: Quem \u00e9 ouvido? Quem pode participar da constru\u00e7\u00e3o da sociedade? Quais vozes se tornam vis\u00edveis nesses processos?<\/p><p>Durante dez anos, trabalhei em diversos centros para jovens. L\u00e1, descobri minha paix\u00e3o por empoderar jovens e criar espa\u00e7os onde eles possam expressar suas opini\u00f5es e participar ativamente.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fcb0e38 elementor-invisible\" data-id=\"fcb0e38\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slide-left&quot;,&quot;animation_delay&quot;:50}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc031b3 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"bc031b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2023\/05\/shape-38.png\" alt=\"Sobre a Forma 4\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-129a5c1 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"129a5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/7Ativo-6.png\" alt=\"7Ativo 6\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c5d631 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4c5d631\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slide-down&quot;,&quot;_animation_delay&quot;:50}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1143\" height=\"1600\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450.jpg\" class=\"attachment-full size-full wp-image-23705\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450.jpg 1143w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450-214x300.jpg 214w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450-732x1024.jpg 732w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450-768x1075.jpg 768w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450-1097x1536.jpg 1097w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/06\/fcf138c0-add1-419b-b807-a740ce05f450-9x12.jpg 9w\" sizes=\"(max-width: 1143px) 100vw, 1143px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-835ce16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"835ce16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca9521e elementor-invisible\" data-id=\"ca9521e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8908184 edublink-br-tp-none elementor-invisible elementor-widget elementor-widget-edublink-heading\" data-id=\"8908184\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Efeito<\/span><h3 class=\"heading\">O que atrav\u00e9s de<mark> meu trabalho ser\u00e1 criado<\/mark>\npode<\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p>N\u00e3o se trata de fornecer respostas prontas. Trata-se de abrir espa\u00e7os onde as pessoas possam ouvir, refletir e desenvolver novas formas de colabora\u00e7\u00e3o.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-532718f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"532718f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dbfbb42 elementor-invisible\" data-id=\"dbfbb42\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa98719 elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"fa98719\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-top\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"ri ri-number-1\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Mais <br>participa\u00e7\u00e3o<\/h5><div class=\"edublink-icon-box-details\"><p>As pessoas s\u00e3o incentivadas a contribuir com suas opini\u00f5es e a participar ativamente dos processos de defini\u00e7\u00e3o.<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4d5a3d0 elementor-invisible\" data-id=\"4d5a3d0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69f2006 elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"69f2006\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-top\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"ri ri-number-2\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Maior diversidade de perspectivas<\/h5><div class=\"edublink-icon-box-details\"><p>Diferentes experi\u00eancias tornam-se vis\u00edveis e s\u00e3o integradas de forma produtiva na colabora\u00e7\u00e3o.<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6cf021a elementor-invisible\" data-id=\"6cf021a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-487ea16 elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"487ea16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-top\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"ri ri-number-3\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Maior certeza na a\u00e7\u00e3o<\/h5><div class=\"edublink-icon-box-details\"><p>Conflitos e incertezas s\u00e3o tornados vis\u00edveis, refletidos e integrados \u00e0 colabora\u00e7\u00e3o.<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8f90dc4 elementor-invisible\" data-id=\"8f90dc4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195dfee elementor-invisible elementor-widget elementor-widget-edublink-icon-box\" data-id=\"195dfee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-icon-box-wrapper edublink-icon-box-icon edublink-icon-box-icon-position-top\"><div class=\"edublink-icon-box-icon edublink-icon-box-enable\"><i aria-hidden=\"true\" class=\"ri ri-number-4\"><\/i><\/div><div class=\"edublink-icon-box-content\"><h5 class=\"edublink-icon-box-title\">Maior conscientiza\u00e7\u00e3o sobre a diversidade<\/h5><div class=\"edublink-icon-box-details\"><p>As organiza\u00e7\u00f5es est\u00e3o desenvolvendo uma vis\u00e3o mais sens\u00edvel em rela\u00e7\u00e3o \u00e0 participa\u00e7\u00e3o, ao senso de pertencimento e \u00e0s quest\u00f5es estruturais.<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0029b44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0029b44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fbeeec0\" data-id=\"fbeeec0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5cc03f elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile about-us-3-main elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"a5cc03f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-color edublink-mouse-track-item\"><span data-depth=\"\"><span class=\"edublink-animation-widget-color\"><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0bdf06 edublink-br-tp-none elementor-invisible elementor-widget elementor-widget-edublink-heading\" data-id=\"e0bdf06\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Efeito<\/span><h3 class=\"heading\">O que atrav\u00e9s de<mark> meu trabalho ser\u00e1 criado<\/mark>\npode<\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p>N\u00e3o se trata de fornecer respostas prontas. Trata-se de abrir espa\u00e7os onde as pessoas possam ouvir, refletir e desenvolver novas formas de colabora\u00e7\u00e3o.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4d85992 e-flex e-con-boxed e-con e-parent\" data-id=\"4d85992\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-91e3be1 e-con-full e-flex e-con e-child\" data-id=\"91e3be1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd5afb elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2fd5afb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-layer-group\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d8301eb e-con-full e-flex e-con e-child\" data-id=\"d8301eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cd70ae elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5cd70ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Conex\u00e3o interdisciplinar<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121112d elementor-widget elementor-widget-text-editor\" data-id=\"121112d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Um mundo com mais humanidade, empatia e coragem para realmente ver e ouvir diferentes perspectivas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4a73bd0 e-flex e-con-boxed e-con e-parent\" data-id=\"4a73bd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-33c3d1d e-con-full e-flex e-con e-child\" data-id=\"33c3d1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9aaf4b6 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9aaf4b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hand-holding-heart\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-39533a9 e-con-full e-flex e-con e-child\" data-id=\"39533a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51d2fc5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"51d2fc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Interativo e pr\u00e1tico<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b420fc elementor-widget elementor-widget-text-editor\" data-id=\"3b420fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meus formatos n\u00e3o s\u00e3o palestras. S\u00e3o participativos, reflexivos e adaptados ao contexto espec\u00edfico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-8fa2b19 e-flex e-con-boxed e-con e-parent\" data-id=\"8fa2b19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7f47676 e-con-full e-flex e-con e-child\" data-id=\"7f47676\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-629bf71 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"629bf71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d580fde e-con-full e-flex e-con e-child\" data-id=\"d580fde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0dec824 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0dec824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Uma perspectiva vivida sobre a diversidade<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73e60a8 elementor-widget elementor-widget-text-editor\" data-id=\"73e60a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Minha pr\u00f3pria trajet\u00f3ria como migrante confere ao meu trabalho uma credibilidade e profundidade que v\u00e3o al\u00e9m do conhecimento puramente te\u00f3rico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3ed8d86 e-flex e-con-boxed e-con e-parent\" data-id=\"3ed8d86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c99c1f2 e-con-full e-flex e-con e-child\" data-id=\"c99c1f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51a3b77 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"51a3b77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cb19fd7 e-con-full e-flex e-con e-child\" data-id=\"cb19fd7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cc629 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c6cc629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Flex\u00edvel e em todo o pa\u00eds<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-662bdec elementor-widget elementor-widget-text-editor\" data-id=\"662bdec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Workshops (4h ou 7h), online e presenciais \u2013 em toda a Alemanha e no Brasil.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-986ab1c\" data-id=\"986ab1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2381cc1 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"2381cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/7Ativo-7.png\" alt=\"7Ativo 7\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b8b727 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default\" data-id=\"1b8b727\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-acc040c\" data-id=\"acc040c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf28759 edublink-br-tp-none elementor-invisible elementor-widget elementor-widget-edublink-heading\" data-id=\"cf28759\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">Efeito<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aac87fc elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"aac87fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\"&quot;Eu n\u00e3o desenvolvo um programa padr\u00e3o. Eu desenvolvo um formato que se adapta \u00e0 sua organiza\u00e7\u00e3o, ao seu p\u00fablico-alvo e ao seu desafio atual.&quot;\"<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1671faf elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1671faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Quer pretenda experimentar um workshop inicial ou esteja a planear um processo de desenvolvimento mais aprofundado, come\u00e7amos com uma conversa focada nas suas necessidades espec\u00edficas.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc35d6 elementor-widget__width-initial elementor-widget elementor-widget-edublink-button\" data-id=\"9cc35d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-small edublink-button-icon-position-\">Workshop (4h \/ 7h)<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c237fb0 elementor-widget__width-initial elementor-widget elementor-widget-edublink-button\" data-id=\"c237fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-small edublink-button-icon-position-\">Pacote de treinamento<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5327a0 elementor-widget__width-initial elementor-widget elementor-widget-edublink-button\" data-id=\"e5327a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-small edublink-button-icon-position-\">Consultoria<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c04a2eb elementor-widget__width-initial elementor-widget elementor-widget-edublink-button\" data-id=\"c04a2eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-small edublink-button-icon-position-\">Palestra \/ Apresenta\u00e7\u00e3o Principal<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac41ba elementor-widget__width-initial elementor-widget elementor-widget-edublink-button\" data-id=\"2ac41ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-small edublink-button-icon-position-\">Online e presencial<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e46ae1 elementor-widget elementor-widget-image\" data-id=\"0e46ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"591\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Vertical-PrincipalAtivo-4.png\" class=\"attachment-large size-large wp-image-22662\" alt=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\" srcset=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Vertical-PrincipalAtivo-4.png 798w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Vertical-PrincipalAtivo-4-600x554.png 600w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Vertical-PrincipalAtivo-4-300x277.png 300w, https:\/\/julikrolop.com\/wp-content\/uploads\/2026\/05\/Vertical-PrincipalAtivo-4-768x709.png 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-719bd9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"719bd9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7761cf4\" data-id=\"7761cf4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02e9140 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-edublink-animation\" data-id=\"02e9140\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2023\/05\/shape-12.png\" alt=\"forma-12\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df54afa elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-edublink-animation\" data-id=\"df54afa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2023\/05\/shape-06.png\" alt=\"forma-06\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4e63f0 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-edublink-animation\" data-id=\"d4e63f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-3\"><img decoding=\"async\" src=\"https:\/\/julikrolop.com\/wp-content\/uploads\/2023\/05\/shape-04-1.png\" alt=\"Forma de Her\u00f3i 7\" title=\"Treinamento em Diversidade e Educa\u00e7\u00e3o Pol\u00edtica | Juli Krolop\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a4e5cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a4e5cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c96c860 elementor-hidden-mobile\" data-id=\"c96c860\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f45a34d elementor-widget elementor-widget-heading\" data-id=\"f45a34d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Moldando processos em conjunto:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-285b3cf elementor-widget elementor-widget-edublink-button\" data-id=\"285b3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-custom edublink-button-size-custom edublink-button-icon-position-after\" href=\"mailto:anfragen@julikrolop.com\">Enviar e-mail<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-96de344 elementor-hidden-mobile\" data-id=\"96de344\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e22ad40 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"e22ad40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ou<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2e7fabf\" data-id=\"2e7fabf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49447a5 elementor-widget elementor-widget-heading\" data-id=\"49447a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Workshop, consultoria ou palestra?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-123052c elementor-widget elementor-widget-edublink-button\" data-id=\"123052c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-curved edublink-button-size-custom edublink-button-icon-position-after default-style\" href=\"#\">Solicitar colabora\u00e7\u00e3o<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcBER JULI KROLOP Ich bin Trainerin f\u00fcr Demokratie, Diversity und Jugendbeteiligung und begleite Organisationen dabei, diese Werte wirklich zu leben. \u00a0\u00a0Diversity Training\u00a0\u00a0Demokratiebildung\u00a0 Jugendbeteiligung\u00a0\u00a0Politische Bildung Anfrage senden Zusammenarbeit NGOs \u2022 Hochschulen \u2022 \u00d6ffentliche Institutionen Workshops und Projekte in ganz Deutschland 15+ Jahre Erfahrung Workshops &amp; Trainings Deutschland &amp; Brasilien Hochschulen, NGOs &amp; Kommunen Meine \u00dcberzeugung Warum&#8230;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10265","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/pages\/10265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/comments?post=10265"}],"version-history":[{"count":67,"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/pages\/10265\/revisions"}],"predecessor-version":[{"id":23718,"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/pages\/10265\/revisions\/23718"}],"wp:attachment":[{"href":"https:\/\/julikrolop.com\/pt\/wp-json\/wp\/v2\/media?parent=10265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}